{"id":28,"count":41,"description":"","link":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/category\/business-owners\/online-reviews\/","name":"Online Reviews","slug":"online-reviews","taxonomy":"category","parent":199,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Online Reviews Archives - SeniorAdvisor.com Blog<\/title>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online Reviews Archives - SeniorAdvisor.com Blog\" \/>\n<meta property=\"og:site_name\" content=\"SeniorAdvisor.com Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/\",\"url\":\"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/\",\"name\":\"Online Reviews Archives - SeniorAdvisor.com Blog\",\"isPartOf\":{\"@id\":\"http:\/\/10.40.48.3\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/10.40.48.3\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog for Business Owners\",\"item\":\"https:\/\/44.224.116.111\/blog\/category\/business-owners\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Online Reviews\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/10.40.48.3\/blog\/#website\",\"url\":\"http:\/\/10.40.48.3\/blog\/\",\"name\":\"SeniorAdvisor.com Blog\",\"description\":\"Empowering Families in their Search for Care\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/10.40.48.3\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online Reviews Archives - SeniorAdvisor.com Blog","og_locale":"en_US","og_type":"article","og_title":"Online Reviews Archives - SeniorAdvisor.com Blog","og_site_name":"SeniorAdvisor.com Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/","url":"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/","name":"Online Reviews Archives - SeniorAdvisor.com Blog","isPartOf":{"@id":"http:\/\/10.40.48.3\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.prod.senioradvisor.com\/blog\/category\/business-owners\/online-reviews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/10.40.48.3\/blog\/"},{"@type":"ListItem","position":2,"name":"Blog for Business Owners","item":"https:\/\/44.224.116.111\/blog\/category\/business-owners\/"},{"@type":"ListItem","position":3,"name":"Online Reviews"}]},{"@type":"WebSite","@id":"http:\/\/10.40.48.3\/blog\/#website","url":"http:\/\/10.40.48.3\/blog\/","name":"SeniorAdvisor.com Blog","description":"Empowering Families in their Search for Care","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/10.40.48.3\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/wp-json\/wp\/v2\/categories\/28"}],"collection":[{"href":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/wp-json\/wp\/v2\/categories\/199"}],"wp:post_type":[{"href":"https:\/\/d30braiqprupoq.cloudfront.net\/blog\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}